{"id":29897,"date":"2024-06-07T11:55:07","date_gmt":"2024-06-07T09:55:07","guid":{"rendered":"https:\/\/www1.varify.io\/?p=29897"},"modified":"2026-03-24T12:05:37","modified_gmt":"2026-03-24T11:05:37","slug":"ga4-audience-evaluation","status":"publish","type":"post","link":"https:\/\/www1.varify.io\/es\/userdocumentation\/ga4-audience-evaluation\/","title":{"rendered":"GA4 Evaluaci\u00f3n de la audiencia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"29897\" class=\"elementor elementor-29897\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-f85bc89 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f85bc89\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3067d42\" data-id=\"3067d42\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c1df0a elementor-widget elementor-widget-sidebar\" data-id=\"1c1df0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"sidebar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<li id=\"elementor-library-3\" class=\"widget widget_elementor-library\">\t\t<div data-elementor-type=\"single-post\" data-elementor-id=\"23913\" class=\"elementor elementor-23913\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-e6fc2db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e6fc2db\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d76346\" data-id=\"1d76346\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a169aa elementor-widget elementor-widget-eael-advanced-search\" data-id=\"2a169aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-advanced-search.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-adv-search-wrapper\">\n            <div id=\"eael-advanced-search-widget-2a169aa\" class=\"eael-advanced-search-widget\">\n                <form data-settings=\"{&quot;post_per_page&quot;:&quot;5&quot;,&quot;search_among_taxonomies&quot;:&quot;yes&quot;,&quot;search_among_sku&quot;:&quot;no&quot;,&quot;show_popular_keyword&quot;:0,&quot;show_category&quot;:1,&quot;show_content_image&quot;:1,&quot;show_search_result_all_results&quot;:1,&quot;result_on_new_tab&quot;:&quot;no&quot;,&quot;show_product_price&quot;:&quot;&quot;,&quot;include_current_page&quot;:&quot;yes&quot;,&quot;current_post_id&quot;:29897,&quot;exclude&quot;:[&quot;12&quot;,&quot;103&quot;],&quot;post_type&quot;:[&quot;post&quot;]}\" method=\"POST\" name=\"eael-advanced-search-form-2a169aa\" class=\"eael-advanced-search-form eael-advanced-search-form-style-1\">\n                    <div class=\"eael-advanced-search-wrap\">\n                        <span class=\"eael-adv-search-loader\"><\/span>\n                        <span class=\"eael-adv-search-close\"><i class=\"fas fa-times\"><\/i><\/span>\n                        <span class=\"icon \"><i class=\"fas fa-search\"><\/i><\/span>\n\n                        <input type=\"text\"\n                               placeholder=\"Suchbegriff eingeben\"\n                               class=\"eael-advanced-search\" autocomplete=\"off\" name=\"eael_advanced_search\">\n                    <\/div>\n\t\t\t\t\t                        <div class=\"eael-advance-search-select\">\n                            <span class=\"icon fas fa-chevron-down\"><\/span>\n\t\t\t\t\t\t\t<select name=\"eael-adv-search-cate-list\" class=\"eael-adv-search-cate\"><option value=''><\/option><option value='1'>Allgemein<\/option><option value='105'>Competitor comparison<\/option><option value='54'>Editor Probleme<\/option><option value='41'>Experiment erstellen<\/option><option value='52'>Experiment Start und Ausspielung<\/option><option value='43'>Experts<\/option><option value='36'>Get started<\/option><option value='108'>Integrationen<\/option><option value='21'>Nutzerdokumentation<\/option><option value='106'>Security<\/option><option value='104'>Success Stories<\/option><option value='40'>Targeting<\/option><option value='53'>Tracking und Auswertung<\/option><option value='37'>Tracking-Auswertung<\/option><option value='49'>Troubleshooting<\/option><option value='42'>Visueller Editor<\/option><option value='38'>Web Analytics Integrationen<\/option><option value='44'>Weitere Inhalte<\/option><option value='39'>Weitere Integrationen<\/option><option value='55'>WordPress<\/option><\/select>                        <\/div>\n\t\t\t\t\t                                            <button class=\"eael-advanced-search-button\">Suche<\/button>\n                                    <\/form>\n\n\t\t\t\t\n\t\t\t\t        <div class=\"eael-advanced-search-result\">\n            <div class=\"eael-advanced-search-popular-keyword\">\n\t\t\t\t<h1 class=\"eael-advanced-search-popular-keyword-text\">Popular Keywords<\/h1>                <div class=\"eael-popular-keyword-content\"><\/div>\n            <\/div>\n            <div class=\"eael-advanced-search-category\">\n\t\t\t\t<h1 class=\"eael-advanced-search-category-text\">Support article<\/h1>                <div class=\"eael-popular-category-content\"><\/div>\n            <\/div>\n\t\t\t<div class=\"eael-advanced-search-total-results-section\">\n\t\t\t\t\t\t\t\t<p class=\"eael-advanced-search-total-results-wrap\">\n\t\t\t\t\tTotal <span class=\"eael-advanced-search-total-results-count\"><\/span> Results\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n            <div class=\"eael-advanced-search-content eael-item-style-1\">\n            <\/div>\n            <div class=\"eael-advanced-search-not-found\">\n                <p>No Record Found<\/p><\/div>\n            <div class=\"eael-advanced-search-load-more\">\n\t\t\t\t<a \tclass=\"eael-advanced-search-load-more-button\"\n                \thref=\"#\">View All Results<\/a>\n            <\/div>\n        <\/div>\n\n\t\t            <\/div>\n        <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/li>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00e2fae elementor-widget elementor-widget-heading\" data-id=\"00e2fae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Audiencebasierte Auswertung in GA4<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35f60b4 elementor-widget elementor-widget-table-of-contents\" data-id=\"35f60b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;headings_by_tags&quot;:[&quot;h2&quot;,&quot;h3&quot;],&quot;exclude_headings_by_selector&quot;:&quot;.h2-sidebar&quot;,&quot;marker_view&quot;:&quot;bullets&quot;,&quot;icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;no_headings_message&quot;:&quot;No headings were found on this page.&quot;,&quot;hierarchical_view&quot;:&quot;yes&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<h2 class=\"elementor-toc__header-title\">\n\t\t\t\tInhaltsverzeichnis\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__35f60b4\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<i class=\"elementor-toc__spinner eicon-animation-spin eicon-loading\" aria-hidden=\"true\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f3d80c elementor-widget elementor-widget-heading\" data-id=\"1f3d80c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kurz &amp; Knapp<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a049dd7 elementor-widget elementor-widget-text-editor\" data-id=\"a049dd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Audiences k\u00f6nnen als Vergleichsm\u00f6glichkeit bei GA4 Standardreports eingesetzt werden. Es ist au\u00dferdem m\u00f6glich, damit Echtzeitdaten zu monitoren. Zudem hast du die M\u00f6glichkeit eigene Berichte anzulegen, wie z.B. \u00fcber unsere A\/B Testing Report Vorlage.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6ad82f elementor-widget elementor-widget-html\" data-id=\"d6ad82f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"tutorial-card\">\n  <div class=\"tutorial-card-inner\">\n    <div class=\"tutorial-card-left\">\n      <div class=\"tutorial-card-icon\">\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#FFFFFF\"><path d=\"M480-120 200-272v-240L40-600l440-240 440 240v320h-80v-276l-80 44v240L480-120Zm0-332 274-148-274-148-274 148 274 148Zm0 241 200-108v-151L480-360 280-470v151l200 108Zm0-241Zm0 90Zm0 0Z\"\/><\/svg>\n      <\/div>\n      <div>\n        <p class=\"tutorial-card-label\">Step-by-Step Tutorial<\/p>\n        <p class=\"tutorial-card-title\">Audiencebasierte Auswertung in GA4<\/p>\n      <\/div>\n    <\/div>\n    <a class=\"tutorial-card-cta\" href=\"https:\/\/app.storylane.io\/share\/hegodiv7urgw\" target=\"_blank\" rel=\"noopener noreferrer\">\n  <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#FFFFFF\">\n    <path d=\"M320-200v-560l440 280-440 280Zm80-280Zm0 134 210-134-210-134v268Z\"\/>\n  <\/svg>\n  Tutorial starten\n<\/a>\n  <\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47cf47e elementor-widget elementor-widget-spacer\" data-id=\"47cf47e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84ce7e9 elementor-widget elementor-widget-heading\" data-id=\"84ce7e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Anlegen von Audience Vergleichen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca7c1ee elementor-widget elementor-widget-image\" data-id=\"ca7c1ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1312\" height=\"632\" src=\"https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports.png\" class=\"attachment-full size-full wp-image-30375\" alt=\"\" srcset=\"https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports.png 1312w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports-300x145.png 300w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports-1024x493.png 1024w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports-768x370.png 768w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports-18x9.png 18w\" sizes=\"(max-width: 1312px) 100vw, 1312px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da42e26 elementor-widget elementor-widget-text-editor\" data-id=\"da42e26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bevor du dir <strong>Echtzeitdaten<\/strong> oder andere <strong>Standardreports<\/strong> unter Zuhilfenahme von Audiences ansehen kannst, ist es notwendig, dass du zun\u00e4chst <strong>einen oder mehrere Vergleiche anlegst<\/strong>.<\/p><p><strong>Wechsele in der linken Navigationsleiste auf den Bereich: Reports<\/strong><\/p><ol><li>Klicke oberhalb deiner Reports in h\u00f6he der Datumszeile auf <strong>Vergleich hinzuf\u00fcgen<\/strong><\/li><li>Klicke auf &#8220;Neu hinzuf\u00fcgen&#8221;<\/li><li>W\u00e4hle bei der &#8220;Dimension&#8221; <em>Audience name<\/em> aus<\/li><li>Selektiere bei &#8220;Match Type&#8221; <em>exactly matches<\/em><\/li><li>W\u00e4hle bei &#8220;Value&#8221; den Namen deiner Zielgruppe aus. Deine Audiences werden ebenfalls direkt vorgeschlagen.<ul><li>Wenn du das Varify.io\u00ae interne GA4 Reporting nutzt, dann wurde die Audience automatisch angelegt.<\/li><li>Der Audience Name ist immer nach folgendem Schema angelegt: Varify-{Experiment-ID}:{Variation-ID} &#8211; beispielsweise: Varify-7826:9456<\/li><li>Nach dieser Methode kannst du auch eigene angelegte Audiences auswerten.<\/li><\/ul><\/li><li>Klicke danach auf &#8220;\u00dcbernehmen&#8221;<\/li><li>Du kannst nun noch weitere Audiences als Vergleich hinzuf\u00fcgen, wenn du das m\u00f6chtest. Gehe dabei genau nach den vorherig beschriebenen Schritten vor.<\/li><\/ol><div>\u00a0<\/div><div>Die Audiences, die du zum Vergleich heranziehst erscheinen am obern Bildschirmrand und werden entsprechend farblich in den Reports hervorgehoben.<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3622c9 elementor-widget elementor-widget-image\" data-id=\"b3622c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1702\" height=\"578\" src=\"https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports10.png\" class=\"attachment-full size-full wp-image-30650\" alt=\"\" srcset=\"https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports10.png 1702w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports10-300x102.png 300w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports10-1024x348.png 1024w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports10-768x261.png 768w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports10-1536x522.png 1536w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports10-18x6.png 18w\" sizes=\"(max-width: 1702px) 100vw, 1702px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e9b588 elementor-widget elementor-widget-spacer\" data-id=\"1e9b588\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84973bf elementor-widget elementor-widget-heading\" data-id=\"84973bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">So benutzt du Audience Vergleiche<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86bf33f elementor-widget elementor-widget-heading\" data-id=\"86bf33f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Auswertung von Experiment Echtzeitdaten mit Hilfe von Audiences in GA4<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2a64b9 elementor-widget elementor-widget-text-editor\" data-id=\"d2a64b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Du m\u00f6chtest kontrollieren, ob die Daten deiner Experimente und Varianten in Echtzeit in GA4 getrackt werden? Dann nutze unter Zu\u00adhil\u00adfe\u00adnah\u00adme von Audiences die Funktion &#8220;Vergleiche&#8221; im Bereich Reports.\u00a0<\/p><p>Wechsele auf den Bereich: Echtzeitdaten<\/p><ol><li>Lege, wie oben gezeigt, die Audiences zum Vergleichen an<\/li><li>Achte darauf, dass der Vergleich \u00fcber den Toggle Switch aktiviert ist<\/li><li>Nun solltest du sehen, ob bereits Testteilnehmer in deinen Audiences getrackt werden<\/li><li>Die Anzeige des Trackings kann nach Setup einer Audience mehrere Minuten dauern<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd021b3 elementor-widget elementor-widget-image\" data-id=\"dd021b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1817\" height=\"527\" src=\"https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports8.png\" class=\"attachment-full size-full wp-image-30634\" alt=\"\" srcset=\"https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports8.png 1817w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports8-300x87.png 300w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports8-1024x297.png 1024w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports8-768x223.png 768w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports8-1536x445.png 1536w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports8-18x5.png 18w\" sizes=\"(max-width: 1817px) 100vw, 1817px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48f3e76 elementor-widget elementor-widget-spacer\" data-id=\"48f3e76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3817f76 elementor-widget elementor-widget-heading\" data-id=\"3817f76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Auswertung von Standardreports mit Hilfe von Audiences in GA4<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90511b9 elementor-widget elementor-widget-text-editor\" data-id=\"90511b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nutze Audiences um die Varianten deiner A\/B Tests miteinander in deinen GA4 Standard Reports zu vergleichen. Nachdem du die Vergleiche, wie oben erkl\u00e4rt, angelegt hast, kannst du alle deine Standard Reports unter dem Bereich Reports \u00f6ffnen und deine A\/B Testergebnisse miteinander vergleichen.<\/p><p>Du kannst den Audience-Vergleich auch in selbst erstellten Standard Reports nutzen. Wir haben f\u00fcr dich einen A\/B Test Report f\u00fcr dich erstellt, den du mit wenigen klicks aktivieren kannst.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42a6633 elementor-widget elementor-widget-image\" data-id=\"42a6633\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1563\" height=\"548\" src=\"https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports5.png\" class=\"attachment-full size-full wp-image-30418\" alt=\"\" srcset=\"https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports5.png 1563w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports5-300x105.png 300w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports5-1024x359.png 1024w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports5-768x269.png 768w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports5-1536x539.png 1536w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports5-18x6.png 18w\" sizes=\"(max-width: 1563px) 100vw, 1563px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7da34a6 elementor-widget elementor-widget-spacer\" data-id=\"7da34a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b645e0b elementor-widget elementor-widget-heading\" data-id=\"b645e0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Varify A\/B Test Standard Report<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99a697b elementor-widget elementor-widget-text-editor\" data-id=\"99a697b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir haben f\u00fcr dich einen A\/B Test Standardreport erstellt, den du mit wenigen Klicks in dein GA4 integrieren kannst. \u00dcber diesen Report kannst du ganz einfach \u00fcber die Experiment ID deine Varianten miteinander vergleichen und die wichtigsten Kennzahlen einsehen.\u00a0<\/p><p>Neben den typischen GA4 Metriken kannst du \u00fcber diesen Bericht auch einzelne\/benutzerdefinierte Events anzeigen und auswerten<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ead9fd elementor-widget elementor-widget-heading\" data-id=\"9ead9fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1. Berichte \u00fcber URL erstellen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f55fae3 elementor-widget elementor-widget-text-editor\" data-id=\"f55fae3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Durch eine Erg\u00e4nzung der URL an der richtigen Stelle, kann der gew\u00fcnschte Bericht mit einem Klick erstellt werden. Erg\u00e4nze dazu in der URL des Google Analytics 4 Dashboards hinter der Property ID den Teil f\u00fcr die Berichterstellung.<\/p><ol><li>Entferne den URL-Teil nach der Property ID in der URL (nach \/p12345678\/).<\/li><li>Erg\u00e4nze den URL-Teil, den wir dir hier bereitstellen.<\/li><li>Speicher den aufgerufenen Report ab -&gt; Varify A\/B Testing Report<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8f8396 elementor-widget elementor-widget-code-highlight\" data-id=\"f8f8396\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"code-highlight.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"prismjs-default copy-to-clipboard \">\n\t\t\t<pre data-line=\"\" class=\"highlight-height language-markup line-numbers\">\n\t\t\t\t<code readonly=\"true\" class=\"language-markup\">\n\t\t\t\t\t<xmp>assetlibrary\/explorer\/new?params=_u..nav%3Dmaui%26_r.explorerCard..dimensions%3D%5B%22audienceName%22%5D%26_r.explorerCard..seldim%3D%5B%22audienceName%22%5D%26_r.explorerCard..metrics%3D%5B%22totalUsers%22,%22checkouts%22,%22purchases%22,%22conversions%22,%22userConversionRate%22,%22eventCount%22%5D%26_r.explorerCard..selmet%3D%5B%22totalUsers%22,%22checkouts%22%5D%26_r.explorerCard..sortKey%3DtotalUsers%26_r.explorerCard..isAscending%3Dfalse&r=new-report<\/xmp>\n\t\t\t\t<\/code>\n\t\t\t<\/pre>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efe3ce8 elementor-widget elementor-widget-image\" data-id=\"efe3ce8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1075\" height=\"415\" src=\"https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/Group-1121.png\" class=\"attachment-full size-full wp-image-29976\" alt=\"\" srcset=\"https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/Group-1121.png 1075w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/Group-1121-300x116.png 300w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/Group-1121-1024x395.png 1024w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/Group-1121-768x296.png 768w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/Group-1121-18x7.png 18w\" sizes=\"(max-width: 1075px) 100vw, 1075px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ebbedd elementor-widget elementor-widget-spacer\" data-id=\"7ebbedd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5a6891 elementor-widget elementor-widget-text-editor\" data-id=\"e5a6891\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nachdem du die Seite mit dem erg\u00e4nzten URL-Teil geladen hast \u00f6ffnet sich ein Report, den du editieren kannst. hier musst du nichts weiter tun, als auf &#8220;Speichern&#8221; zu klicken.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abca587 elementor-widget elementor-widget-heading\" data-id=\"abca587\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2. Bericht in einer Sammlung ver\u00f6ffentlichen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3be2e3f elementor-widget elementor-widget-text-editor\" data-id=\"3be2e3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nachdem du den Report gespeichert hast, kannst du ihn in der Report Bibliothek einer bestehenden Report-Sammlung hinzuf\u00fcgen, oder du erstellt eine eigene Sammlung f\u00fcr A\/B Testing Reports.<\/p><ol><li>Gehe zu deiner Report Bibliothek<\/li><li>Klicke auf &#8220;Neue Sammlung erstellen&#8221; und erstelle einen leere Sammlung<\/li><li>Benenne die Sammlung &#8220;A\/B Testing&#8221;<\/li><li>Erstelle eine neue Bereichs\u00fcberschrift &#8220;Varify A\/B Testing&#8221;<\/li><li>Ziehe deinen erstellten Report in den Bereich<\/li><li>Speichere die Sammlung<\/li><li>Ver\u00f6ffentliche nun in der Bibliothek die Sammlung (Klicke auf die drei Punkte bei der Sammlung und w\u00e4hle &#8220;Ver\u00f6ffentlichen&#8221;)<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-c417b1f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c417b1f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0cabf76\" data-id=\"0cabf76\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b30bef elementor-widget elementor-widget-image\" data-id=\"7b30bef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1716\" height=\"1175\" src=\"https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports2.png\" class=\"attachment-full size-full wp-image-30397\" alt=\"\" srcset=\"https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports2.png 1716w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports2-300x205.png 300w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports2-1024x701.png 1024w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports2-768x526.png 768w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports2-1536x1052.png 1536w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports2-18x12.png 18w\" sizes=\"(max-width: 1716px) 100vw, 1716px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-73cf9b3\" data-id=\"73cf9b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14b4425 elementor-widget elementor-widget-image\" data-id=\"14b4425\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"556\" src=\"https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports3.png\" class=\"attachment-full size-full wp-image-30398\" alt=\"\" srcset=\"https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports3.png 472w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports3-255x300.png 255w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports3-10x12.png 10w\" sizes=\"(max-width: 472px) 100vw, 472px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3003b1 elementor-widget elementor-widget-spacer\" data-id=\"a3003b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca1d792 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"ca1d792\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3. Experiment im Bericht auswerten<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c22c863 elementor-widget elementor-widget-text-editor\" data-id=\"c22c863\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wenn du die Bericht Sammlung ver\u00f6ffentlicht hast, erscheint diese in der Spallte der Standardreports. Gehe hier zum frisch erstellten Bericht.<\/p><p>Um ein Experiment auszuwerten, kannst du nun einfach die Experiment ID in das Suchfeld f\u00fcr den Audience Name eingeben. Anschlie\u00dfend werden alle Varianten, inkl. Original des entsprechenden Experiment angezeigt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3df99f9 elementor-widget elementor-widget-image\" data-id=\"3df99f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1556\" height=\"921\" src=\"https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports9.png\" class=\"attachment-full size-full wp-image-30638\" alt=\"\" srcset=\"https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports9.png 1556w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports9-300x178.png 300w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports9-1024x606.png 1024w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports9-768x455.png 768w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports9-1536x909.png 1536w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports9-18x12.png 18w\" sizes=\"(max-width: 1556px) 100vw, 1556px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d87053d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"d87053d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4. Bericht individuell anpassen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4341eb2 elementor-widget elementor-widget-text-editor\" data-id=\"4341eb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Du kannst den erstellten Report ganz einfach nach deinen W\u00fcnschen anpassen. Klicke dazu einfach auf das Stift-Icon. Anschlie\u00dfend \u00f6ffnet sich das Men\u00fc zum bearbeiten.\u00a0<\/p><p>\u00dcber den Punkt &#8220;Metriken&#8221; kannst du weitere Metriken hinzuf\u00fcgen, oder bereits hinzugef\u00fcgte Metriken entfernen. Speichere anschlie\u00dfende die \u00c4nderungen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d389e46 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"d389e46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5. Benutzerdefinierte Events anzeigen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afafc20 elementor-widget elementor-widget-text-editor\" data-id=\"afafc20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wenn du benutzerdefinierte Events auswerten m\u00f6chtest, kannst du dies ganz einfach \u00fcbder den Varify Report tun. Sollte deine Metrik als benutzerdefinierte Metrik hinterlegt sein, kannst du diese ganz einfach wie in Punkt 4 als Metrik hinzuf\u00fcgen.<\/p><p>Ist dein Event nicht als benutzerdefinierte Metrik angelegt kannst du \u00fcber die Metrik &#8220;Event Count&#8221; des Reports ein bestimmtes Event anzeigen lassen. Standardm\u00e4\u00dfig werden hier alle Events angezeigt.<\/p><ol><li>Klicke dazu auf das Dropdown unter &#8220;Event Count&#8221;<\/li><li>W\u00e4hle anschlie\u00dfend das gew\u00fcnschte Event im sich \u00f6ffnenden Fenster aus<\/li><li style=\"margin-bottom: 15px;\">Event Count zeigt nun ausschlie\u00dflich die Zahlen f\u00fcr das gew\u00e4hlte Event<\/li><\/ol><p>Das gleiche funktioniert gilt auch, f\u00fcr die Metrik &#8220;Key Events&#8221;. Auch hier werden standardm\u00e4\u00dfig alle Key Event angezeigt. M\u00f6chtest du nur ein bestimmtes sehen, kannst du es ebenfalls einzeln ausw\u00e4hlen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4589b57 elementor-widget elementor-widget-image\" data-id=\"4589b57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1028\" height=\"297\" src=\"https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports7.png\" class=\"attachment-full size-full wp-image-30420\" alt=\"\" srcset=\"https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports7.png 1028w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports7-300x87.png 300w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports7-1024x296.png 1024w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports7-768x222.png 768w, https:\/\/www1.varify.io\/wp-content\/uploads\/2024\/06\/AudiencesInStandardReports7-18x5.png 18w\" sizes=\"(max-width: 1028px) 100vw, 1028px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0d36c1 elementor-widget elementor-widget-spacer\" data-id=\"d0d36c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-766d3f1 elementor-widget elementor-widget-spacer\" data-id=\"766d3f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1db956a\" data-id=\"1db956a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-453cf3e elementor-widget elementor-widget-sidebar\" data-id=\"453cf3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"sidebar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<li id=\"elementor-library-2\" class=\"widget widget_elementor-library\">\t\t<div data-elementor-type=\"single-post\" data-elementor-id=\"23790\" class=\"elementor elementor-23790\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-e4670c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e4670c6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-231dec3\" data-id=\"231dec3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67c00f2 elementor-widget elementor-widget-heading\" data-id=\"67c00f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/varify.io\/de\/userdocumentation\/\" target=\"_blank\" rel=\"noopener\">Nutzerdokumentation<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b87b89c elementor-widget elementor-widget-n-accordion\" data-id=\"b87b89c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1930\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-1930\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Erste Schritte <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1930\" class=\"elementor-element elementor-element-3819167 e-con-full e-flex e-con e-child\" data-id=\"3819167\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1930\" class=\"elementor-element elementor-element-42ba248 e-flex e-con-boxed e-con e-child\" data-id=\"42ba248\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-805dc5d elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"805dc5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;dropdown&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-chevron-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-805dc5d\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-45448\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/how-varify-works\/\" class=\"elementor-item\" tabindex=\"-1\">So funktioniert Varify.io<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23830\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/implementacion-del-fragmento-varify\/\" class=\"elementor-item\" tabindex=\"-1\">Varify Snippet \u2013 Implementierung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40608\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/tracking-setup\/\" class=\"elementor-item\" tabindex=\"-1\">Tracking einrichten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-25116\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/iniciar-una-prueba\/\" class=\"elementor-item\" tabindex=\"-1\">Starte einen A\/A Test und \u00fcberpr\u00fcfe das Tracking\u200b<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40572\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/a-b-crear-experimento-de-prueba\/\" class=\"elementor-item\" tabindex=\"-1\">Experiment erstellen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-25866\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/extension-del-navegador-chrome\/\" class=\"elementor-item\" tabindex=\"-1\">Chrome Browser Erweiterung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-45578\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/best-practice\/\" class=\"elementor-item\" tabindex=\"-1\">Best Practice<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-47082\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/cro-ai-audit\/\" class=\"elementor-item\" tabindex=\"-1\">CRO AI Audit<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1931\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1931\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Tracking &amp; Web Analytics Integrationen <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1931\" class=\"elementor-element elementor-element-93f153a e-con-full e-flex e-con e-child\" data-id=\"93f153a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bacbb76 elementor-nav-menu__align-start elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"bacbb76\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-bacbb76\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40606\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/tracking-setup\/\" class=\"elementor-item\">Tracking mit Varify<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33939\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/seguimiento-con-gtm-google-tag-manager\/\" class=\"elementor-item\">Manuelle Google Tag Manager Tracking-Integration<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40509\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/automatic-ga4-tracking-integration\/\" class=\"elementor-item\">Automatische GA4 Tracking Integration<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-35528\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/shopify-custom-pixel-integration-via-google-tag-manager\/\" class=\"elementor-item\">Shopify Custom Pixel Integration via Google Tag Manager<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40510\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/shopify-tracking\/\" class=\"elementor-item\">Shopify Tracking<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-42108\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/bigquery\/\" class=\"elementor-item\">BigQuery<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40959\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/posthog-tracking\/\" class=\"elementor-item\">PostHog Auswertungen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33940\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/integracion-de-matomo-mediante-matomo-tag-manager\/\" class=\"elementor-item\">Matomo \u2013 Integration via Matomo Tag Manager<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33941\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/etracker-integration\/\" class=\"elementor-item\">etracker Integration<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33942\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/piwik-pro-integration\/\" class=\"elementor-item\">Piwik Pro Integration<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-37218\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/tracking-via-consent\/\" class=\"elementor-item\">Consent \u2013 Tracking via Consent<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40607\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/advanced-setup-options\/\" class=\"elementor-item\">Advanced Settings<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-bacbb76\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40606\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/tracking-setup\/\" class=\"elementor-item\" tabindex=\"-1\">Tracking mit Varify<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33939\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/seguimiento-con-gtm-google-tag-manager\/\" class=\"elementor-item\" tabindex=\"-1\">Manuelle Google Tag Manager Tracking-Integration<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40509\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/automatic-ga4-tracking-integration\/\" class=\"elementor-item\" tabindex=\"-1\">Automatische GA4 Tracking Integration<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-35528\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/shopify-custom-pixel-integration-via-google-tag-manager\/\" class=\"elementor-item\" tabindex=\"-1\">Shopify Custom Pixel Integration via Google Tag Manager<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40510\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/shopify-tracking\/\" class=\"elementor-item\" tabindex=\"-1\">Shopify Tracking<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-42108\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/bigquery\/\" class=\"elementor-item\" tabindex=\"-1\">BigQuery<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40959\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/posthog-tracking\/\" class=\"elementor-item\" tabindex=\"-1\">PostHog Auswertungen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33940\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/integracion-de-matomo-mediante-matomo-tag-manager\/\" class=\"elementor-item\" tabindex=\"-1\">Matomo \u2013 Integration via Matomo Tag Manager<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33941\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/etracker-integration\/\" class=\"elementor-item\" tabindex=\"-1\">etracker Integration<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33942\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/piwik-pro-integration\/\" class=\"elementor-item\" tabindex=\"-1\">Piwik Pro Integration<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-37218\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/tracking-via-consent\/\" class=\"elementor-item\" tabindex=\"-1\">Consent \u2013 Tracking via Consent<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40607\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/advanced-setup-options\/\" class=\"elementor-item\" tabindex=\"-1\">Advanced Settings<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1932\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1932\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Experiment erstellen <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1932\" class=\"elementor-element elementor-element-4c0f900 e-con-full e-flex e-con e-child\" data-id=\"4c0f900\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7bf1a99 elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"7bf1a99\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-7bf1a99\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33931\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/a-b-crear-experimento-de-prueba\/\" class=\"elementor-item\">Experiment erstellen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-47097\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/prompt-based-experiments\/\" class=\"elementor-item\">Prompt Based Experiments (PBX)<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33932\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/a-b-pruebas-garantia-de-calidad\/\" class=\"elementor-item\">Qualit\u00e4tssicherung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40569\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/iniciar-y-detener-experimentos\/\" class=\"elementor-item\">Starten und stoppen von Experimenten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-45968\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/schedule-experiments\/\" class=\"elementor-item\">Zeitgesteuertes Starten und Stoppen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40198\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/pruebas-de-redireccion-y-division-de-url\/\" class=\"elementor-item\">Redirect &#038; Split URL Testing<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33933\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/variante-duplicada\/\" class=\"elementor-item\">Variante duplizieren<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33935\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/experimentar-con-diversas-variantes\/\" class=\"elementor-item\">Experiment mit mehreren Varianten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33936\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/rename-experiments-and-variations\/\" class=\"elementor-item\">Umbenennen von Experimenten und Varianten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-35042\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/create-multi-page-experiments\/\" class=\"elementor-item\">Multi-Page Experiment erstellen<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-7bf1a99\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33931\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/a-b-crear-experimento-de-prueba\/\" class=\"elementor-item\" tabindex=\"-1\">Experiment erstellen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-47097\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/prompt-based-experiments\/\" class=\"elementor-item\" tabindex=\"-1\">Prompt Based Experiments (PBX)<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33932\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/a-b-pruebas-garantia-de-calidad\/\" class=\"elementor-item\" tabindex=\"-1\">Qualit\u00e4tssicherung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40569\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/iniciar-y-detener-experimentos\/\" class=\"elementor-item\" tabindex=\"-1\">Starten und stoppen von Experimenten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-45968\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/schedule-experiments\/\" class=\"elementor-item\" tabindex=\"-1\">Zeitgesteuertes Starten und Stoppen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40198\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/pruebas-de-redireccion-y-division-de-url\/\" class=\"elementor-item\" tabindex=\"-1\">Redirect &#038; Split URL Testing<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33933\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/variante-duplicada\/\" class=\"elementor-item\" tabindex=\"-1\">Variante duplizieren<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33935\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/experimentar-con-diversas-variantes\/\" class=\"elementor-item\" tabindex=\"-1\">Experiment mit mehreren Varianten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33936\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/rename-experiments-and-variations\/\" class=\"elementor-item\" tabindex=\"-1\">Umbenennen von Experimenten und Varianten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-35042\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/create-multi-page-experiments\/\" class=\"elementor-item\" tabindex=\"-1\">Multi-Page Experiment erstellen<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1933\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1933\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Targeting <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1933\" class=\"elementor-element elementor-element-e403a77 e-con-full e-flex e-con e-child\" data-id=\"e403a77\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d08d6d7 elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"d08d6d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-d08d6d7\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-24547\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/segmentacion-del-publico\/\" class=\"elementor-item\">Audience Targeting<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-42062\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/mutual-exclusion-of-experiments\/\" class=\"elementor-item\">Gegenseitiger Ausschluss von Experimenten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-26934\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/page-targeting\/\" class=\"elementor-item\">Page Targeting<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-d08d6d7\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-24547\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/segmentacion-del-publico\/\" class=\"elementor-item\" tabindex=\"-1\">Audience Targeting<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-42062\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/mutual-exclusion-of-experiments\/\" class=\"elementor-item\" tabindex=\"-1\">Gegenseitiger Ausschluss von Experimenten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-26934\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/page-targeting\/\" class=\"elementor-item\" tabindex=\"-1\">Page Targeting<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1934\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1934\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Reporting &amp; Auswertung <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1934\" class=\"elementor-element elementor-element-66d7d7c e-con-full e-flex e-con e-child\" data-id=\"66d7d7c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8ea8bf7 elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"8ea8bf7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-8ea8bf7\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-29790\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/ga4-connection\/\" class=\"elementor-item\">Reporting in Varify.io<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-42107\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/bigquery\/\" class=\"elementor-item\">BigQuery<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-34874\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/segments-and-filter\/\" class=\"elementor-item\">Reports segmentieren und filtern<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40782\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/share-report\/\" class=\"elementor-item\">Report teilen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-30433\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/ga4-audience-evaluation\/\" class=\"elementor-item\">Audiencebasierte Auswertung in GA4<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23805\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/evaluacion-de-los-resultados-en-ga-4\/\" class=\"elementor-item\">Segmentbasierte Auswertung in GA 4<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-41178\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/posthog-tracking\/\" class=\"elementor-item\">PostHog Tracking<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-43502\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/export-experiment-results\/\" class=\"elementor-item\">Exportieren der Experimentergebnisse aus Varify<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-28921\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/analisis-de-los-resultados-de-matomo\/\" class=\"elementor-item\">Matomo \u2013 Ergebnisauswertung\u200b<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-31116\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/etracker-evaluation\/\" class=\"elementor-item\">etracker Auswertung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-25005\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/calcular-la-significacion\/\" class=\"elementor-item\">Signifikanz berechnen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-29286\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/custom-click-events\/\" class=\"elementor-item\">Benutzerdefinierte Klick Events<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-26075\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/evalue-las-conversiones-personalizadas-en-informes-exploratorios\/\" class=\"elementor-item\">Custom Events in explorativen Reports auswerten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-34870\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/ga4-cross-domain-tracking\/\" class=\"elementor-item\">GA4 \u2013 Cross-Domain Tracking<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-8ea8bf7\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-29790\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/ga4-connection\/\" class=\"elementor-item\" tabindex=\"-1\">Reporting in Varify.io<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-42107\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/bigquery\/\" class=\"elementor-item\" tabindex=\"-1\">BigQuery<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-34874\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/segments-and-filter\/\" class=\"elementor-item\" tabindex=\"-1\">Reports segmentieren und filtern<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40782\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/share-report\/\" class=\"elementor-item\" tabindex=\"-1\">Report teilen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-30433\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/ga4-audience-evaluation\/\" class=\"elementor-item\" tabindex=\"-1\">Audiencebasierte Auswertung in GA4<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23805\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/evaluacion-de-los-resultados-en-ga-4\/\" class=\"elementor-item\" tabindex=\"-1\">Segmentbasierte Auswertung in GA 4<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-41178\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/posthog-tracking\/\" class=\"elementor-item\" tabindex=\"-1\">PostHog Tracking<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-43502\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/export-experiment-results\/\" class=\"elementor-item\" tabindex=\"-1\">Exportieren der Experimentergebnisse aus Varify<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-28921\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/analisis-de-los-resultados-de-matomo\/\" class=\"elementor-item\" tabindex=\"-1\">Matomo \u2013 Ergebnisauswertung\u200b<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-31116\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/etracker-evaluation\/\" class=\"elementor-item\" tabindex=\"-1\">etracker Auswertung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-25005\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/calcular-la-significacion\/\" class=\"elementor-item\" tabindex=\"-1\">Signifikanz berechnen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-29286\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/custom-click-events\/\" class=\"elementor-item\" tabindex=\"-1\">Benutzerdefinierte Klick Events<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-26075\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/evalue-las-conversiones-personalizadas-en-informes-exploratorios\/\" class=\"elementor-item\" tabindex=\"-1\">Custom Events in explorativen Reports auswerten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-34870\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/ga4-cross-domain-tracking\/\" class=\"elementor-item\" tabindex=\"-1\">GA4 \u2013 Cross-Domain Tracking<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1935\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1935\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Visueller Editor <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1935\" class=\"elementor-element elementor-element-20b5ed4 e-con-full e-flex e-con e-child\" data-id=\"20b5ed4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e781b2c elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"e781b2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-e781b2c\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16611\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/refuerzo-de-campana-flecha-arriba\/\" class=\"elementor-item\">Campaign Booster: Arrow Up<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16606\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/campaign-booster-exit-intent-layer\/\" class=\"elementor-item\">Campaign Booster: Exit Intent Layer<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16605\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/barra-informativa-de-refuerzo-de-campana\/\" class=\"elementor-item\">Campaign Booster: Information Bar<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16610\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/notificacion-de-refuerzo-de-campana\/\" class=\"elementor-item\">Campaign Booster: Notification<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16604\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/barra-usp-de-refuerzo-de-campana\/\" class=\"elementor-item\">Campaign Booster: USP Bar<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16612\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/anadir-enlace-de-destino\/\" class=\"elementor-item\">Add Link Target<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16820\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/modo-de-navegacion\/\" class=\"elementor-item\">Browse Mode<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-27017\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/custom-selector\/\" class=\"elementor-item\">Custom Selector Picker<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-17426\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/editar-contenido\/\" class=\"elementor-item\">Edit Content<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-17421\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/editar-texto\/\" class=\"elementor-item\">Edit Text<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-29029\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/move-elements\/\" class=\"elementor-item\">Elemente verschieben<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33902\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/hide-element-2\/\" class=\"elementor-item\">Hide Element<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16600\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/insercion-de-palabras-clave\/\" class=\"elementor-item\">Keyword Insertion<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-22263\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/pruebas-de-redireccion-y-division-de-url\/\" class=\"elementor-item\">Redirect &#038; Split URL Testing<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-15997\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/eliminar-elemento\/\" class=\"elementor-item\">Remove Element<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-17423\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/reemplazar-imagen\/\" class=\"elementor-item\">Replace Image<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-24757\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/conmutador-de-dispositivos-sensible\/\" class=\"elementor-item\">Responsive Device Switcher<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16614\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/editar-estilo\/\" class=\"elementor-item\">Style &#038; Layout \u00c4nderungen<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-e781b2c\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16611\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/refuerzo-de-campana-flecha-arriba\/\" class=\"elementor-item\" tabindex=\"-1\">Campaign Booster: Arrow Up<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16606\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/campaign-booster-exit-intent-layer\/\" class=\"elementor-item\" tabindex=\"-1\">Campaign Booster: Exit Intent Layer<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16605\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/barra-informativa-de-refuerzo-de-campana\/\" class=\"elementor-item\" tabindex=\"-1\">Campaign Booster: Information Bar<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16610\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/notificacion-de-refuerzo-de-campana\/\" class=\"elementor-item\" tabindex=\"-1\">Campaign Booster: Notification<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16604\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/barra-usp-de-refuerzo-de-campana\/\" class=\"elementor-item\" tabindex=\"-1\">Campaign Booster: USP Bar<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16612\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/anadir-enlace-de-destino\/\" class=\"elementor-item\" tabindex=\"-1\">Add Link Target<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16820\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/modo-de-navegacion\/\" class=\"elementor-item\" tabindex=\"-1\">Browse Mode<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-27017\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/custom-selector\/\" class=\"elementor-item\" tabindex=\"-1\">Custom Selector Picker<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-17426\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/editar-contenido\/\" class=\"elementor-item\" tabindex=\"-1\">Edit Content<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-17421\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/editar-texto\/\" class=\"elementor-item\" tabindex=\"-1\">Edit Text<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-29029\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/move-elements\/\" class=\"elementor-item\" tabindex=\"-1\">Elemente verschieben<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33902\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/hide-element-2\/\" class=\"elementor-item\" tabindex=\"-1\">Hide Element<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16600\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/insercion-de-palabras-clave\/\" class=\"elementor-item\" tabindex=\"-1\">Keyword Insertion<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-22263\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/pruebas-de-redireccion-y-division-de-url\/\" class=\"elementor-item\" tabindex=\"-1\">Redirect &#038; Split URL Testing<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-15997\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/eliminar-elemento\/\" class=\"elementor-item\" tabindex=\"-1\">Remove Element<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-17423\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/reemplazar-imagen\/\" class=\"elementor-item\" tabindex=\"-1\">Replace Image<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-24757\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/conmutador-de-dispositivos-sensible\/\" class=\"elementor-item\" tabindex=\"-1\">Responsive Device Switcher<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16614\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/editar-estilo\/\" class=\"elementor-item\" tabindex=\"-1\">Style &#038; Layout \u00c4nderungen<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1936\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"7\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1936\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Weitere Integrationen <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1936\" class=\"elementor-element elementor-element-f7b8157 e-con-full e-flex e-con e-child\" data-id=\"f7b8157\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e5ecc6 elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"7e5ecc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-7e5ecc6\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-38379\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/integrations\/\" class=\"elementor-item\">Integrationen<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-7e5ecc6\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-38379\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/integrations\/\" class=\"elementor-item\" tabindex=\"-1\">Integrationen<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1937\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"8\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1937\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Experten Funktionen <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1937\" class=\"elementor-element elementor-element-16b7cc0 e-con-full e-flex e-con e-child\" data-id=\"16b7cc0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-84c0e5c elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"84c0e5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-84c0e5c\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23799\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/anadir-css\/\" class=\"elementor-item\">Add CSS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-28652\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/add-html\/\" class=\"elementor-item\">Add HTML<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23800\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/anadir-js\/\" class=\"elementor-item\">Add JavaScript<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-24893\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/anadir-reinicio-javascript\/\" class=\"elementor-item\">Add JavaScript Reset<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-45449\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/anti-flicker-script\/\" class=\"elementor-item\">Anti-Flicker-Script<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23802\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/ayudantes-de-codificacion\/\" class=\"elementor-item\">Code Helpers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23801\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/editar-html\/\" class=\"elementor-item\">Edit HTML<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44570\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/experiment-api\/\" class=\"elementor-item\">Experiment API<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-84c0e5c\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23799\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/anadir-css\/\" class=\"elementor-item\" tabindex=\"-1\">Add CSS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-28652\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/add-html\/\" class=\"elementor-item\" tabindex=\"-1\">Add HTML<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23800\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/anadir-js\/\" class=\"elementor-item\" tabindex=\"-1\">Add JavaScript<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-24893\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/anadir-reinicio-javascript\/\" class=\"elementor-item\" tabindex=\"-1\">Add JavaScript Reset<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-45449\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/anti-flicker-script\/\" class=\"elementor-item\" tabindex=\"-1\">Anti-Flicker-Script<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23802\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/ayudantes-de-codificacion\/\" class=\"elementor-item\" tabindex=\"-1\">Code Helpers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23801\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/editar-html\/\" class=\"elementor-item\" tabindex=\"-1\">Edit HTML<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44570\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/experiment-api\/\" class=\"elementor-item\" tabindex=\"-1\">Experiment API<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1938\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"9\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1938\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Sicherheit <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1938\" class=\"elementor-element elementor-element-f0ff639 e-con-full e-flex e-con e-child\" data-id=\"f0ff639\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d01e3e elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"0d01e3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-0d01e3e\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44691\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/activity-log\/\" class=\"elementor-item\">Activity Log<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44689\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/active-sessions\/\" class=\"elementor-item\">Active Sessions<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44690\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/login-history\/\" class=\"elementor-item\">Login History<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44688\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/multi-factor-authentication\/\" class=\"elementor-item\">Multi Factor Authentication (MFA)<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-0d01e3e\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44691\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/activity-log\/\" class=\"elementor-item\" tabindex=\"-1\">Activity Log<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44689\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/active-sessions\/\" class=\"elementor-item\" tabindex=\"-1\">Active Sessions<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44690\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/login-history\/\" class=\"elementor-item\" tabindex=\"-1\">Login History<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44688\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/multi-factor-authentication\/\" class=\"elementor-item\" tabindex=\"-1\">Multi Factor Authentication (MFA)<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1939\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"10\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1939\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Troubleshooting \/ FAQ <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1939\" class=\"elementor-element elementor-element-6f00e06 e-con-full e-flex e-con e-child\" data-id=\"6f00e06\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-76affdf elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"76affdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-76affdf\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-39607\"><a href=\"https:\/\/www1.varify.io\/de\/userdocumentation\/troubleshooting-faq\/\" class=\"elementor-item\">Troubleshooting (alle)<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-39610\"><a href=\"https:\/\/www1.varify.io\/de\/userdocumentation\/troubleshooting-faq\/?open=tracking\" class=\"elementor-item\">Probleme mit Tracking und Auswertung<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-39608\"><a href=\"https:\/\/www1.varify.io\/de\/userdocumentation\/troubleshooting-faq\/?open=start-and-execution\" class=\"elementor-item\">Probleme mit Experiment Start\/Auslieferung<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-39609\"><a href=\"https:\/\/www1.varify.io\/de\/userdocumentation\/troubleshooting-faq\/?open=editor\" class=\"elementor-item\">Probleme mit dem Editor<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-76affdf\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-39607\"><a href=\"https:\/\/www1.varify.io\/de\/userdocumentation\/troubleshooting-faq\/\" class=\"elementor-item\" tabindex=\"-1\">Troubleshooting (alle)<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-39610\"><a href=\"https:\/\/www1.varify.io\/de\/userdocumentation\/troubleshooting-faq\/?open=tracking\" class=\"elementor-item\" tabindex=\"-1\">Probleme mit Tracking und Auswertung<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-39608\"><a href=\"https:\/\/www1.varify.io\/de\/userdocumentation\/troubleshooting-faq\/?open=start-and-execution\" class=\"elementor-item\" tabindex=\"-1\">Probleme mit Experiment Start\/Auslieferung<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-39609\"><a href=\"https:\/\/www1.varify.io\/de\/userdocumentation\/troubleshooting-faq\/?open=editor\" class=\"elementor-item\" tabindex=\"-1\">Probleme mit dem Editor<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-19310\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"11\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-19310\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Weitere n\u00fctzliche Inhalte <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-19310\" class=\"elementor-element elementor-element-581cfe9 e-con-full e-flex e-con e-child\" data-id=\"581cfe9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-19310\" class=\"elementor-element elementor-element-1ca04d0 e-flex e-con-boxed e-con e-child\" data-id=\"1ca04d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cbf2145 elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"cbf2145\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;dropdown&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-cbf2145\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-34844\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/create-subscription\/\" class=\"elementor-item\" tabindex=\"-1\">Zahlung &#038; Subscription<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33821\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/agency-account\/\" class=\"elementor-item\" tabindex=\"-1\">Agency Account<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33930\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/tutoriales-paso-a-paso\/\" class=\"elementor-item\" tabindex=\"-1\">Step-by-Step Tutorials<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-34025\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/multi-factor-authentication\/\" class=\"elementor-item\" tabindex=\"-1\">Multi Factor Authentication (MFA)<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-34846\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Shopify Optimierung<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-38896\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/shopify-tracking\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Shopify Tracking<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-34848\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/shopify-theme-test-with-varify-io\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Shopify Theme testen mit Varify.io<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40480\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/test-shopify-pdp-templates\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Shopify \u2013 PDP Templates testen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-38712\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/shopify-price-test\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Shopify \u2013 Einrichten eines Preis Tests<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-31795\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/modulo-pdp-para-tienda-shopify-2\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Module f\u00fcr Shopify Store kostenlos testen<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-38612\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">WordPress Optimierung<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-38897\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/ab-test-hidden-wordpress-content\/\" class=\"elementor-sub-item\" tabindex=\"-1\">WordPress Versteckte Inhalte per Einblendung testen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-38613\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/wordpress-redirect-split-url-testing\/\" class=\"elementor-sub-item\" tabindex=\"-1\">WordPress Redirect &#038; Split URL Testing<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-34845\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">F\u00fcr Nerds<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-34847\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/varify-debug\/\" class=\"elementor-sub-item\" tabindex=\"-1\">varify.debug<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-36281\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/varify-success-and-varify-error\/\" class=\"elementor-sub-item\" tabindex=\"-1\">varify_success und varify_error<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-34342\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/cname\/\" class=\"elementor-sub-item\" tabindex=\"-1\">CNAME<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44569\"><a href=\"https:\/\/www1.varify.io\/es\/userdocumentation\/experiment-api\/\" class=\"elementor-item\" tabindex=\"-1\">Experiment API<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbf03e6 elementor-widget elementor-widget-spacer\" data-id=\"dbf03e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-ee229d0 e-flex e-con-boxed e-con e-parent\" data-id=\"ee229d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0bba753 elementor-widget elementor-widget-html\" data-id=\"0bba753\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>window.varify.helpers.waitFor(\n  \".elementor-23790 .elementor-element.elementor-element-231dec3 > .elementor-element-populated\",\n  function () {\n    (function () {\n      var SCOPE_SEL =\n        \".elementor-23790 .elementor-element.elementor-element-231dec3 > .elementor-element-populated\";\n      var ACTIVE_SEL = \"a.elementor-item-active\";\n\n      function getScope() {\n        return document.querySelector(SCOPE_SEL);\n      }\n\n      function closeEverything(scope) {\n        Array.prototype.slice.call(scope.querySelectorAll(\"details[open]\")).forEach(function (d) {\n          d.open = false;\n        });\n\n        Array.prototype.slice\n          .call(scope.querySelectorAll(\"button[aria-expanded], a[aria-expanded]\"))\n          .forEach(function (t) {\n            t.setAttribute(\"aria-expanded\", \"false\");\n          });\n\n        Array.prototype.slice\n          .call(scope.querySelectorAll(\"li.menu-item-has-children, li.page_item_has_children, li.has-children\"))\n          .forEach(function (li) {\n            li.classList.remove(\"open\", \"is-open\", \"is-active-path\", \"is-active\");\n          });\n\n        Array.prototype.slice\n          .call(\n            scope.querySelectorAll(\n              \".elementor-nav-menu--dropdown, .elementor-nav-menu__container, .elementor-nav-menu\"\n            )\n          )\n          .forEach(function (el) {\n            el.classList.remove(\"is-open\");\n            if (el.matches(\".elementor-nav-menu__container, .elementor-nav-menu--dropdown\")) {\n              el.setAttribute(\"aria-hidden\", \"true\");\n            }\n          });\n\n        Array.prototype.slice.call(scope.querySelectorAll(\"ul.sub-menu\")).forEach(function (ul) {\n          ul.classList.remove(\"is-open\");\n          ul.setAttribute(\"aria-hidden\", \"true\");\n          ul.setAttribute(\"aria-expanded\", \"false\");\n        });\n      }\n\n      function forceOpenSubmenuForActiveLink(activeLink) {\n        var subMenuUl = activeLink.closest(\"ul.sub-menu\");\n        if (!subMenuUl) return;\n\n        subMenuUl.classList.add(\"is-open\");\n        subMenuUl.setAttribute(\"aria-hidden\", \"false\");\n        subMenuUl.setAttribute(\"aria-expanded\", \"true\");\n\n        var toggle = null;\n        var ulId = subMenuUl.getAttribute(\"id\");\n        if (ulId) toggle = document.querySelector('[aria-controls=\"' + ulId + '\"]');\n\n        if (!toggle) {\n          var parentLi = subMenuUl.closest(\"li.menu-item-has-children, li.page_item_has_children, li.has-children\");\n          if (parentLi) toggle = parentLi.querySelector(\":scope > a, :scope > button\");\n        }\n\n        if (toggle) toggle.setAttribute(\"aria-expanded\", \"true\");\n\n        var parentLi2 = subMenuUl.closest(\"li.menu-item-has-children, li.page_item_has_children, li.has-children\");\n        if (parentLi2) parentLi2.classList.add(\"open\", \"is-open\");\n\n        var container = subMenuUl.closest(\".elementor-nav-menu__container, .elementor-nav-menu--dropdown\");\n        if (container) {\n          container.classList.add(\"is-open\");\n          container.setAttribute(\"aria-hidden\", \"false\");\n        }\n      }\n\n      function openParentsForLink(link) {\n        var el = link;\n\n        while (el && el !== document.body) {\n          if (el.tagName === \"DETAILS\") el.open = true;\n\n          if (el.tagName === \"UL\" && el.classList && el.classList.contains(\"sub-menu\")) {\n            el.classList.add(\"is-open\");\n            el.setAttribute(\"aria-hidden\", \"false\");\n            el.setAttribute(\"aria-expanded\", \"true\");\n\n            var ulId = el.getAttribute(\"id\");\n            if (ulId) {\n              var controller = document.querySelector('[aria-controls=\"' + ulId + '\"]');\n              if (controller) controller.setAttribute(\"aria-expanded\", \"true\");\n            }\n          }\n\n          var directToggle =\n            el.querySelector(\":scope > button[aria-expanded], :scope > a[aria-expanded]\") || null;\n          if (directToggle) directToggle.setAttribute(\"aria-expanded\", \"true\");\n\n          if (el.classList) {\n            if (el.matches(\"li.menu-item-has-children\")) el.classList.add(\"open\");\n            if (el.matches(\"li.menu-item-has-children, li.page_item_has_children, li.has-children\"))\n              el.classList.add(\"is-open\");\n\n            if (el.matches(\".elementor-item, .elementor-nav-menu-item\")) el.classList.add(\"is-active-path\");\n\n            if (el.matches(\".elementor-nav-menu__container, .elementor-nav-menu--dropdown\")) {\n              el.classList.add(\"is-open\");\n              el.setAttribute(\"aria-hidden\", \"false\");\n            }\n          }\n\n          el = el.parentElement;\n        }\n      }\n\n      function applyOnce() {\n        var scope = getScope();\n        if (!scope) return;\n\n        closeEverything(scope);\n\n        var actives = scope.querySelectorAll(ACTIVE_SEL);\n        if (!actives || actives.length === 0) return;\n\n        Array.prototype.slice.call(actives).forEach(function (a) {\n          a.setAttribute(\"aria-current\", \"page\");\n          forceOpenSubmenuForActiveLink(a);\n          openParentsForLink(a);\n        });\n      }\n\n      function enhanceMenuBehavior() {\n        var scope = getScope();\n        if (!scope) return;\n\n        if (scope.dataset.varifyMenuEnhanced === \"1\") return;\n        scope.dataset.varifyMenuEnhanced = \"1\";\n\n        function hasOpenMenus() {\n          return !!scope.querySelector(\n            \"ul.sub-menu.is-open, li.menu-item-has-children.is-open, li.menu-item-has-children.open\"\n          );\n        }\n\n        function isInScope(t) {\n          return t && (t === scope || scope.contains(t));\n        }\n\n        function stopIfOutsideWhileOpen(e) {\n          if (!hasOpenMenus()) return;\n          if (isInScope(e.target)) return;\n\n          e.stopPropagation();\n          if (typeof e.stopImmediatePropagation === \"function\") e.stopImmediatePropagation();\n        }\n\n        [\"pointerdown\", \"mousedown\", \"touchstart\", \"click\"].forEach(function (evt) {\n          document.addEventListener(evt, stopIfOutsideWhileOpen, true);\n        });\n\n        scope.addEventListener(\n          \"click\",\n          function (e) {\n            var subLink = e.target.closest(\"ul.sub-menu a\");\n            if (subLink && scope.contains(subLink)) {\n              e.stopPropagation();\n              if (typeof e.stopImmediatePropagation === \"function\") e.stopImmediatePropagation();\n            }\n          },\n          true\n        );\n\n        scope.addEventListener(\n          \"pointerdown\",\n          function (e) {\n            var toggle = e.target.closest(\"a.has-submenu, a[aria-haspopup='true'], button[aria-haspopup='true']\");\n            if (!toggle || !scope.contains(toggle)) return;\n\n            var li = toggle.closest(\"li.menu-item-has-children, li.page_item_has_children, li.has-children\");\n            if (!li) return;\n\n            Array.prototype.slice\n              .call(scope.querySelectorAll(\"li.menu-item-has-children.open, li.menu-item-has-children.is-open\"))\n              .forEach(function (other) {\n                if (other === li) return;\n\n                other.classList.remove(\"open\", \"is-open\");\n\n                var t = other.querySelector(\":scope > a[aria-expanded], :scope > button[aria-expanded]\");\n                if (t) t.setAttribute(\"aria-expanded\", \"false\");\n\n                var ul = other.querySelector(\":scope > ul.sub-menu\");\n                if (ul) {\n                  ul.classList.remove(\"is-open\");\n                  ul.setAttribute(\"aria-hidden\", \"true\");\n                  ul.setAttribute(\"aria-expanded\", \"false\");\n                }\n              });\n\n            li.classList.add(\"open\", \"is-open\");\n            toggle.setAttribute(\"aria-expanded\", \"true\");\n\n            var ul2 = li.querySelector(\":scope > ul.sub-menu\");\n            if (ul2) {\n              ul2.classList.add(\"is-open\");\n              ul2.setAttribute(\"aria-hidden\", \"false\");\n              ul2.setAttribute(\"aria-expanded\", \"true\");\n            }\n\n            e.stopPropagation();\n            if (typeof e.stopImmediatePropagation === \"function\") e.stopImmediatePropagation();\n          },\n          true\n        );\n\n        scope.addEventListener(\n          \"focusout\",\n          function (e) {\n            if (!hasOpenMenus()) return;\n            \/\/ Fokuswechsel soll nicht das Men\u00fc schlie\u00dfen\n            e.stopPropagation();\n            if (typeof e.stopImmediatePropagation === \"function\") e.stopImmediatePropagation();\n          },\n          true\n        );\n\n        document.addEventListener(\n          \"keydown\",\n          function (e) {\n            if (!hasOpenMenus()) return;\n            \/\/ ESC soll nicht \"alles schlie\u00dfen\"\n            if (e.key === \"Escape\" || e.key === \"Esc\") {\n              e.stopPropagation();\n              if (typeof e.stopImmediatePropagation === \"function\") e.stopImmediatePropagation();\n            }\n          },\n          true\n        );\n      }\n\n      function init() {\n        applyOnce();\n        setTimeout(applyOnce, 150);\n        setTimeout(applyOnce, 600);\n        setTimeout(applyOnce, 1200);\n\n        enhanceMenuBehavior();\n      }\n\n      if (document.readyState === \"loading\") {\n        document.addEventListener(\"DOMContentLoaded\", init);\n      } else {\n        init();\n      }\n    })();\n  }\n);<\/script>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/li>\n<li id=\"custom_html-2\" class=\"widget_text widget widget_custom_html\"><div class=\"textwidget custom-html-widget\"><script>\r\n\/\/ Function to check the URL hash and scroll to the element\r\nfunction checkAndScrollToHash() {\r\n    const urlHash = window.location.hash; \/\/ Get the current URL hash\r\n    if (urlHash) {\r\n        const targetElement = document.querySelector(urlHash); \/\/ Try to find the element matching the hash\r\n        if (targetElement) {\r\n            \/\/ Scroll to the element using scrollIntoView\r\n            targetElement.scrollIntoView({\r\n                behavior: 'smooth',\r\n                block: 'start'\r\n            });\r\n        }\r\n    }\r\n}\r\n\r\n\/\/ Execute the function once, one second after the page loads\r\nsetTimeout(checkAndScrollToHash, 1000);\r\n<\/script>\r\n<\/div><\/li>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Audiencebasierte Auswertung in GA4 Inhaltsverzeichnis Kurz &amp; Knapp Audiences k\u00f6nnen als Vergleichsm\u00f6glichkeit bei GA4 Standardreports eingesetzt werden. Es ist au\u00dferdem m\u00f6glich, damit Echtzeitdaten zu monitoren. Zudem hast du die M\u00f6glichkeit eigene Berichte anzulegen, wie z.B. \u00fcber unsere A\/B Testing Report Vorlage. Step-by-Step Tutorial Audiencebasierte Auswertung in GA4 Tutorial starten Anlegen von Audience Vergleichen Bevor du [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[21,37],"tags":[],"class_list":["post-29897","post","type-post","status-publish","format-standard","hentry","category-userdocumentation","category-tracking-auswertung"],"_links":{"self":[{"href":"https:\/\/www1.varify.io\/es\/wp-json\/wp\/v2\/posts\/29897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www1.varify.io\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www1.varify.io\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www1.varify.io\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www1.varify.io\/es\/wp-json\/wp\/v2\/comments?post=29897"}],"version-history":[{"count":109,"href":"https:\/\/www1.varify.io\/es\/wp-json\/wp\/v2\/posts\/29897\/revisions"}],"predecessor-version":[{"id":45989,"href":"https:\/\/www1.varify.io\/es\/wp-json\/wp\/v2\/posts\/29897\/revisions\/45989"}],"wp:attachment":[{"href":"https:\/\/www1.varify.io\/es\/wp-json\/wp\/v2\/media?parent=29897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www1.varify.io\/es\/wp-json\/wp\/v2\/categories?post=29897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www1.varify.io\/es\/wp-json\/wp\/v2\/tags?post=29897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}